{"id":6794,"date":"2019-05-30T15:20:45","date_gmt":"2019-05-30T18:20:45","guid":{"rendered":"http:\/\/www.proma.com.br\/blog\/?p=6794"},"modified":"2018-12-12T14:25:25","modified_gmt":"2018-12-12T17:25:25","slug":"presentes-diy-para-o-dia-dos-namorados-voce-vai-amar","status":"publish","type":"post","link":"https:\/\/www.proma.com.br\/blog\/presentes-diy-para-o-dia-dos-namorados-voce-vai-amar\/","title":{"rendered":"PRESENTES DIY PARA O DIA DOS NAMORADOS: VOC\u00ca VAI AMAR!"},"content":{"rendered":"<p>O Dia dos Namorados est\u00e1 chegando e voc\u00ea ainda n\u00e3o sabe como presentear o amor da sua vida? Que tal dar um toque pessoal aos mimos do dia <strong>12 de junho<\/strong>?<\/p>\n<p>Confira essas dicas incr\u00edveis!<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-6795\" src=\"http:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/01.png\" alt=\"\" width=\"657\" height=\"585\" srcset=\"https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/01.png 657w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/01-337x300.png 337w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/> <img loading=\"lazy\" class=\"aligncenter size-large wp-image-6796\" src=\"http:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/02.png\" alt=\"\" width=\"584\" height=\"511\" srcset=\"https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/02.png 676w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/02-343x300.png 343w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/> <img loading=\"lazy\" class=\"aligncenter size-large wp-image-6797\" src=\"http:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/03.png\" alt=\"\" width=\"584\" height=\"472\" srcset=\"https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/03.png 721w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/03-371x300.png 371w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/> <img loading=\"lazy\" class=\"aligncenter size-large wp-image-6798\" src=\"http:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/04.png\" alt=\"\" width=\"584\" height=\"482\" srcset=\"https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/04.png 714w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/04-364x300.png 364w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/> <img loading=\"lazy\" class=\"aligncenter size-large wp-image-6799\" src=\"http:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/05.png\" alt=\"\" width=\"584\" height=\"368\" srcset=\"https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/05.png 827w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/05-768x484.png 768w, https:\/\/www.proma.com.br\/blog\/wp-content\/uploads\/2018\/12\/05-476x300.png 476w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/p>\n<p>Vamos colocar essas ideias em pr\u00e1tica para um Dia dos Namorados com muito amor?<\/p>\n<p><strong>Fonte: <\/strong><a href=\"https:\/\/bit.ly\/2Bh8dZ9\" target=\"_blank\" rel=\"noopener\">WePick<\/a><\/p>\n<p><strong>Fotos:\u00a0<\/strong>Reprodu\u00e7\u00e3o\/Pinterest<\/p>\n<p>________<\/p>\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n<ul>\n<li>Mimos para o caf\u00e9 no Dia dos Namorados. <a href=\"http:\/\/www.proma.com.br\/blog\/mimos-para-o-cafe-da-manha-no-dia-dos-namorados\/\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a> e confira.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O Dia dos Namorados est\u00e1 chegando e voc\u00ea ainda n\u00e3o sabe como presentear o amor da sua vida? Que tal dar um toque pessoal aos mimos do dia 12 de junho? Confira essas dicas incr\u00edveis! Vamos colocar essas ideias em&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1143],"tags":[1223,2696,2291,3127],"_links":{"self":[{"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/posts\/6794"}],"collection":[{"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/comments?post=6794"}],"version-history":[{"count":4,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/posts\/6794\/revisions"}],"predecessor-version":[{"id":6803,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/posts\/6794\/revisions\/6803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/media\/6797"}],"wp:attachment":[{"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/media?parent=6794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/categories?post=6794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proma.com.br\/blog\/wp-json\/wp\/v2\/tags?post=6794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}